{"id":2073,"date":"2022-10-21T10:31:28","date_gmt":"2022-10-21T10:31:28","guid":{"rendered":"https:\/\/www.foodsovereignty.org\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\/"},"modified":"2024-01-30T23:05:36","modified_gmt":"2024-01-30T23:05:36","slug":"la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal","status":"publish","type":"post","link":"https:\/\/www.foodsovereignty.org\/es\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\/","title":{"rendered":"La CIP desarrolla una metodolog\u00eda centrada en las personas para supervisar las pol\u00edticas de pesca artesanal"},"content":{"rendered":"<p style=\"text-align: justify;\">En el verano de 2021, los miembros del Grupo Asesor del SSF-GSF, con el apoyo del <strong>Grupo de Trabajo de Pesca del CIP<\/strong>, decidieron desarrollar una metodolog\u00eda para evaluar la aplicaci\u00f3n de las Directrices voluntarias para asegurar la pesca sostenible en peque\u00f1a escala en el contexto de la seguridad alimentaria y la erradicaci\u00f3n de la pobreza; el principal instrumento internacional de las Naciones Unidas para proteger y promover los derechos de los pescadores en peque\u00f1a escala aprobado por el Comit\u00e9 de Pesca de la FAO en 2014.<\/p>\n<p style=\"text-align: justify;\">Las <strong>Directrices PPE<\/strong> son de alcance mundial y de aplicaci\u00f3n local. Sin embargo, casi ocho a\u00f1os despu\u00e9s de la aprobaci\u00f3n de las directrices, hay pocas pruebas emp\u00edricas de la aplicaci\u00f3n real de las Directrices PPE. Al mismo tiempo, las pruebas que apoyan las opiniones de los movimientos y que se\u00f1alan la falta de aplicaci\u00f3n de las Directrices PPE son, por desgracia, limitadas.<\/p>\n<p style=\"text-align: justify;\">La <a href=\"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2023\/05\/ES_PCM.pdf\"><strong>metodolog\u00eda centrada en las personas del CIP<\/strong><\/a> es, de hecho, un proceso participativo para recopilar informaci\u00f3n cualitativa sobre la situaci\u00f3n de los pescadores a peque\u00f1a escala y concienciar sobre las Directrices PPE. Tiene en cuenta todos los diferentes aspectos culturales y sociales de los pescadores a peque\u00f1a escala que suelen ser pasados por alto por las metodolog\u00edas cuantitativas y t\u00e9cnicas. La metodolog\u00eda pretende evaluar en las comunidades y con las comunidades el progreso de la implementaci\u00f3n de las Directrices PPE y examinar las violaciones de los derechos humanos de los pescadores a peque\u00f1a escala en todo el mundo y hasta qu\u00e9 punto los Estados est\u00e1n cumpliendo e implementando las Directrices PPE y los objetivos centrales de las mismas. La evaluaci\u00f3n servir\u00e1 para que los gobiernos rindan cuentas de sus compromisos voluntarios y proporcionar\u00e1 la base para la promoci\u00f3n continua a nivel nacional y regional, as\u00ed como a nivel internacional en la FAO y otros organismos de la ONU.<\/p>\n<p style=\"text-align: justify;\">Con motivo del 35\u00ba per\u00edodo de sesiones del Comit\u00e9 de Pesca (COFI) de la FAO, el Grupo Consultivo (GC) del MSS coordin\u00f3 la elaboraci\u00f3n de <a href=\"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2022\/10\/TNI_report-ES_web.pdf\"><strong>un informe preliminar<\/strong><\/a> destinado a proporcionar algunos datos y an\u00e1lisis iniciales sobre el estado de aplicaci\u00f3n de las directrices del MSS en diferentes pa\u00edses del mundo:\u00a0<em>Evaluaci\u00f3n centrada en las personas de la aplicaci\u00f3n de las Directrices voluntarias para asegurar la pesca sostenible en peque\u00f1a escala<\/em>.\u00a0La evaluaci\u00f3n se basa en la informaci\u00f3n sustantiva proporcionada por las organizaciones de la pesca en peque\u00f1a escala y los pueblos ind\u00edgenas procedentes de 21 pa\u00edses y, aunque la muestra no es representativa de todas las zonas geogr\u00e1ficas, sigue abriendo nuevos caminos como el primer informe centrado en las personas sobre la aplicaci\u00f3n de las Directrices PPE.<\/p>\n<p style=\"text-align: justify;\">Descargue la metodolog\u00eda centrada en las personas del CIP <a href=\"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2023\/05\/ES_PCM.pdf\"><strong>AQU\u00cd<\/strong><\/a><\/p>\n<p style=\"text-align: justify;\">Descargue el informe preliminar <a href=\"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2022\/10\/TNI_report-ES_web.pdf\"><strong>AQU\u00cd<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el verano de 2021, los miembros del Grupo Asesor del SSF-GSF, con el apoyo del Grupo de Trabajo de Pesca del CIP, decidieron desarrollar una metodolog\u00eda para evaluar la aplicaci\u00f3n de las Directrices voluntarias para asegurar la pesca sostenible en peque\u00f1a escala en el contexto de la seguridad alimentaria y la erradicaci\u00f3n de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2458,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[60],"tags":[85,364,361],"class_list":["post-2073","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-food-sovereignty","tag-pesca-a-pequena-escala","tag-pesca-artesanal","regional_processes_tax-africa","regional_processes_tax-asia-pacific","regional_processes_tax-europe-central-asia","regional_processes_tax-latin-america-caribbean","regional_processes_tax-near-east-north-africa","working_groups_tax-fisheries"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La CIP desarrolla una metodolog\u00eda centrada en las personas para supervisar las pol\u00edticas de pesca artesanal - International Planning Committee for Food Sovereignty (IPC)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.foodsovereignty.org\/es\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La CIP desarrolla una metodolog\u00eda centrada en las personas para supervisar las pol\u00edticas de pesca artesanal - International Planning Committee for Food Sovereignty (IPC)\" \/>\n<meta property=\"og:description\" content=\"En el verano de 2021, los miembros del Grupo Asesor del SSF-GSF, con el apoyo del Grupo de Trabajo de Pesca del CIP, decidieron desarrollar una metodolog\u00eda para evaluar la aplicaci\u00f3n de las Directrices voluntarias para asegurar la pesca sostenible en peque\u00f1a escala en el contexto de la seguridad alimentaria y la erradicaci\u00f3n de la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.foodsovereignty.org\/es\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\/\" \/>\n<meta property=\"og:site_name\" content=\"International Planning Committee for Food Sovereignty (IPC)\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-21T10:31:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-30T23:05:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/small-scale-fisheries-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ipc_staging\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ipc_staging\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/es\\\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/es\\\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\\\/\"},\"author\":{\"name\":\"ipc_staging\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/es\\\/#\\\/schema\\\/person\\\/2022da6fc0f89b23596d0a63d82b61e1\"},\"headline\":\"La CIP desarrolla una metodolog\u00eda centrada en las personas para supervisar las pol\u00edticas de pesca artesanal\",\"datePublished\":\"2022-10-21T10:31:28+00:00\",\"dateModified\":\"2024-01-30T23:05:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/es\\\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\\\/\"},\"wordCount\":507,\"image\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/es\\\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.foodsovereignty.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/small-scale-fisheries-2.jpg\",\"keywords\":[\"food sovereignty\",\"pesca a pequena escala\",\"Pesca Artesanal\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/es\\\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\\\/\",\"url\":\"https:\\\/\\\/www.foodsovereignty.org\\\/es\\\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\\\/\",\"name\":\"La CIP desarrolla una metodolog\u00eda centrada en las personas para supervisar las pol\u00edticas de pesca artesanal - International Planning Committee for Food Sovereignty (IPC)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/es\\\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/es\\\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.foodsovereignty.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/small-scale-fisheries-2.jpg\",\"datePublished\":\"2022-10-21T10:31:28+00:00\",\"dateModified\":\"2024-01-30T23:05:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/es\\\/#\\\/schema\\\/person\\\/2022da6fc0f89b23596d0a63d82b61e1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/es\\\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.foodsovereignty.org\\\/es\\\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/es\\\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.foodsovereignty.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/small-scale-fisheries-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.foodsovereignty.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/small-scale-fisheries-2.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/es\\\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.foodsovereignty.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La CIP desarrolla una metodolog\u00eda centrada en las personas para supervisar las pol\u00edticas de pesca artesanal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.foodsovereignty.org\\\/es\\\/\",\"name\":\"International Planning Committee for Food Sovereignty (IPC)\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.foodsovereignty.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/es\\\/#\\\/schema\\\/person\\\/2022da6fc0f89b23596d0a63d82b61e1\",\"name\":\"ipc_staging\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g\",\"caption\":\"ipc_staging\"},\"sameAs\":[\"http:\\\/\\\/_\"],\"url\":\"https:\\\/\\\/www.foodsovereignty.org\\\/es\\\/author\\\/ipc_staging\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La CIP desarrolla una metodolog\u00eda centrada en las personas para supervisar las pol\u00edticas de pesca artesanal - International Planning Committee for Food Sovereignty (IPC)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.foodsovereignty.org\/es\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\/","og_locale":"es_ES","og_type":"article","og_title":"La CIP desarrolla una metodolog\u00eda centrada en las personas para supervisar las pol\u00edticas de pesca artesanal - International Planning Committee for Food Sovereignty (IPC)","og_description":"En el verano de 2021, los miembros del Grupo Asesor del SSF-GSF, con el apoyo del Grupo de Trabajo de Pesca del CIP, decidieron desarrollar una metodolog\u00eda para evaluar la aplicaci\u00f3n de las Directrices voluntarias para asegurar la pesca sostenible en peque\u00f1a escala en el contexto de la seguridad alimentaria y la erradicaci\u00f3n de la [&hellip;]","og_url":"https:\/\/www.foodsovereignty.org\/es\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\/","og_site_name":"International Planning Committee for Food Sovereignty (IPC)","article_published_time":"2022-10-21T10:31:28+00:00","article_modified_time":"2024-01-30T23:05:36+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/small-scale-fisheries-2.jpg","type":"image\/jpeg"}],"author":"ipc_staging","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ipc_staging","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.foodsovereignty.org\/es\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\/#article","isPartOf":{"@id":"https:\/\/www.foodsovereignty.org\/es\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\/"},"author":{"name":"ipc_staging","@id":"https:\/\/www.foodsovereignty.org\/es\/#\/schema\/person\/2022da6fc0f89b23596d0a63d82b61e1"},"headline":"La CIP desarrolla una metodolog\u00eda centrada en las personas para supervisar las pol\u00edticas de pesca artesanal","datePublished":"2022-10-21T10:31:28+00:00","dateModified":"2024-01-30T23:05:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.foodsovereignty.org\/es\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\/"},"wordCount":507,"image":{"@id":"https:\/\/www.foodsovereignty.org\/es\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\/#primaryimage"},"thumbnailUrl":"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/small-scale-fisheries-2.jpg","keywords":["food sovereignty","pesca a pequena escala","Pesca Artesanal"],"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.foodsovereignty.org\/es\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\/","url":"https:\/\/www.foodsovereignty.org\/es\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\/","name":"La CIP desarrolla una metodolog\u00eda centrada en las personas para supervisar las pol\u00edticas de pesca artesanal - International Planning Committee for Food Sovereignty (IPC)","isPartOf":{"@id":"https:\/\/www.foodsovereignty.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.foodsovereignty.org\/es\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\/#primaryimage"},"image":{"@id":"https:\/\/www.foodsovereignty.org\/es\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\/#primaryimage"},"thumbnailUrl":"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/small-scale-fisheries-2.jpg","datePublished":"2022-10-21T10:31:28+00:00","dateModified":"2024-01-30T23:05:36+00:00","author":{"@id":"https:\/\/www.foodsovereignty.org\/es\/#\/schema\/person\/2022da6fc0f89b23596d0a63d82b61e1"},"breadcrumb":{"@id":"https:\/\/www.foodsovereignty.org\/es\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.foodsovereignty.org\/es\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.foodsovereignty.org\/es\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\/#primaryimage","url":"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/small-scale-fisheries-2.jpg","contentUrl":"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/small-scale-fisheries-2.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.foodsovereignty.org\/es\/la-cip-desarrolla-una-metodologia-centrada-en-las-personas-para-supervisar-las-politicas-de-pesca-artesanal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.foodsovereignty.org\/es\/"},{"@type":"ListItem","position":2,"name":"La CIP desarrolla una metodolog\u00eda centrada en las personas para supervisar las pol\u00edticas de pesca artesanal"}]},{"@type":"WebSite","@id":"https:\/\/www.foodsovereignty.org\/es\/#website","url":"https:\/\/www.foodsovereignty.org\/es\/","name":"International Planning Committee for Food Sovereignty (IPC)","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.foodsovereignty.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.foodsovereignty.org\/es\/#\/schema\/person\/2022da6fc0f89b23596d0a63d82b61e1","name":"ipc_staging","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g","caption":"ipc_staging"},"sameAs":["http:\/\/_"],"url":"https:\/\/www.foodsovereignty.org\/es\/author\/ipc_staging\/"}]}},"_links":{"self":[{"href":"https:\/\/www.foodsovereignty.org\/es\/wp-json\/wp\/v2\/posts\/2073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.foodsovereignty.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.foodsovereignty.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.foodsovereignty.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.foodsovereignty.org\/es\/wp-json\/wp\/v2\/comments?post=2073"}],"version-history":[{"count":1,"href":"https:\/\/www.foodsovereignty.org\/es\/wp-json\/wp\/v2\/posts\/2073\/revisions"}],"predecessor-version":[{"id":2841,"href":"https:\/\/www.foodsovereignty.org\/es\/wp-json\/wp\/v2\/posts\/2073\/revisions\/2841"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.foodsovereignty.org\/es\/wp-json\/wp\/v2\/media\/2458"}],"wp:attachment":[{"href":"https:\/\/www.foodsovereignty.org\/es\/wp-json\/wp\/v2\/media?parent=2073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.foodsovereignty.org\/es\/wp-json\/wp\/v2\/categories?post=2073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.foodsovereignty.org\/es\/wp-json\/wp\/v2\/tags?post=2073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}