{"id":1731,"date":"2021-03-24T10:23:23","date_gmt":"2021-03-24T10:23:23","guid":{"rendered":"https:\/\/www.foodsovereignty.org\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\/"},"modified":"2024-01-30T22:58:02","modified_gmt":"2024-01-30T22:58:02","slug":"le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020","status":"publish","type":"post","link":"https:\/\/www.foodsovereignty.org\/fr\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\/","title":{"rendered":"Le 2\u00b0 webinaire ouvert aux parties prenantes de la CDB : \u00ab\u00a0Transition durable de l&rsquo;agriculture et des syst\u00e8mes alimentaires : liens avec le Cadre mondial pour la biodiversit\u00e9 post-2020\u00a0\u00bb."},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Le mardi 23 mars 2021, le <a href=\"https:\/\/www.cbd.int\/article\/stakeholder-open-webinar-agrifood-2021\">deuxi\u00e8me webinaire ouvert aux parties prenantes organis\u00e9 par la Convention sur la biodiversit\u00e9 (CBD)<\/a> s&rsquo;est tenu afin d&rsquo;explorer et d&rsquo;identifier les concepts et les questions cl\u00e9s li\u00e9s \u00e0 l&rsquo;\u00e9laboration du Cadre mondial pour la biodiversit\u00e9 post-2020.  Le webinaire \u00e9tait ax\u00e9 sur \u00ab\u00a0l&rsquo;agriculture durable et la transition des syst\u00e8mes alimentaires : Liens avec le Cadre mondial pour la biodiversit\u00e9 post-2020\u00a0\u00bb. Le CIP, en tant que plateforme mondiale rassemblant les petits producteurs alimentaires impliqu\u00e9s dans la conservation, l&rsquo;utilisation durable, le d\u00e9veloppement et la gouvernance de la biodiversit\u00e9 agricole, a eu l&rsquo;opportunit\u00e9 de participer au webinaire en tant qu&rsquo;intervenant par l&rsquo;interm\u00e9diaire de Tammi Jonas, Pr\u00e9sident de l&rsquo;Australian Food Sovereignty Alliance et l&rsquo;un des coordinateurs du groupe de travail sur la biodiversit\u00e9 agricole du CIP.  Vous trouverez ci-dessous l&rsquo;enregistrement du webinaire et en <a href=\"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2021\/03\/210323_Stakeholder-Open-Webinar_ag-GBF_FRA.pdf\">cliquant ici vous pouvez ouvrir et t\u00e9l\u00e9charger la pr\u00e9sentation<\/a> power point r\u00e9alis\u00e9e \u00e0 l&rsquo;occasion du webinaire.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_video link=\u00a0\u00bbhttps:\/\/www.youtube.com\/watch?v=itrHztqj01g\u00a0\u00bb title=\u00a0\u00bbLe deuxi\u00e8me webinaire ouvert aux parties prenantes de la CDB : Transition durable de l&rsquo;agriculture et des syst\u00e8mes alimentaires : liens avec le Cadre mondial pour la biodiversit\u00e9 post-2020&Prime;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Le mardi 23 mars 2021, le deuxi\u00e8me webinaire ouvert aux parties prenantes organis\u00e9 par la Convention sur la biodiversit\u00e9 (CBD) s&rsquo;est tenu afin d&rsquo;explorer et d&rsquo;identifier les concepts et les questions cl\u00e9s li\u00e9s \u00e0 l&rsquo;\u00e9laboration du Cadre mondial pour la biodiversit\u00e9 post-2020. Le webinaire \u00e9tait ax\u00e9 sur \u00ab\u00a0l&rsquo;agriculture durable et la transition des syst\u00e8mes alimentaires [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2308,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[57],"tags":[],"class_list":["post-1731","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","working_groups_tax-agricultural-biodiversity"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le 2\u00b0 webinaire ouvert aux parties prenantes de la CDB : &quot;Transition durable de l&#039;agriculture et des syst\u00e8mes alimentaires : liens avec le Cadre mondial pour la biodiversit\u00e9 post-2020&quot;. - International Planning Committee for Food Sovereignty (IPC)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.foodsovereignty.org\/fr\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le 2\u00b0 webinaire ouvert aux parties prenantes de la CDB : &quot;Transition durable de l&#039;agriculture et des syst\u00e8mes alimentaires : liens avec le Cadre mondial pour la biodiversit\u00e9 post-2020&quot;. - International Planning Committee for Food Sovereignty (IPC)\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text]Le mardi 23 mars 2021, le deuxi\u00e8me webinaire ouvert aux parties prenantes organis\u00e9 par la Convention sur la biodiversit\u00e9 (CBD) s&rsquo;est tenu afin d&rsquo;explorer et d&rsquo;identifier les concepts et les questions cl\u00e9s li\u00e9s \u00e0 l&rsquo;\u00e9laboration du Cadre mondial pour la biodiversit\u00e9 post-2020. Le webinaire \u00e9tait ax\u00e9 sur \u00ab\u00a0l&rsquo;agriculture durable et la transition des syst\u00e8mes alimentaires [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.foodsovereignty.org\/fr\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"International Planning Committee for Food Sovereignty (IPC)\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-24T10:23:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-30T22:58:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/copertina-eng-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ipc_staging\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ipc_staging\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\\\/\"},\"author\":{\"name\":\"ipc_staging\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/#\\\/schema\\\/person\\\/2022da6fc0f89b23596d0a63d82b61e1\"},\"headline\":\"Le 2\u00b0 webinaire ouvert aux parties prenantes de la CDB : \u00ab\u00a0Transition durable de l&rsquo;agriculture et des syst\u00e8mes alimentaires : liens avec le Cadre mondial pour la biodiversit\u00e9 post-2020\u00a0\u00bb.\",\"datePublished\":\"2021-03-24T10:23:23+00:00\",\"dateModified\":\"2024-01-30T22:58:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\\\/\"},\"wordCount\":264,\"image\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.foodsovereignty.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/copertina-eng-1-1.jpg\",\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\\\/\",\"url\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\\\/\",\"name\":\"Le 2\u00b0 webinaire ouvert aux parties prenantes de la CDB : \\\"Transition durable de l'agriculture et des syst\u00e8mes alimentaires : liens avec le Cadre mondial pour la biodiversit\u00e9 post-2020\\\". - International Planning Committee for Food Sovereignty (IPC)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.foodsovereignty.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/copertina-eng-1-1.jpg\",\"datePublished\":\"2021-03-24T10:23:23+00:00\",\"dateModified\":\"2024-01-30T22:58:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/#\\\/schema\\\/person\\\/2022da6fc0f89b23596d0a63d82b61e1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.foodsovereignty.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/copertina-eng-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.foodsovereignty.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/copertina-eng-1-1.jpg\",\"width\":2000,\"height\":1125},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le 2\u00b0 webinaire ouvert aux parties prenantes de la CDB : &#8220;Transition durable de l&#8217;agriculture et des syst\u00e8mes alimentaires : liens avec le Cadre mondial pour la biodiversit\u00e9 post-2020&#8221;.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/\",\"name\":\"International Planning Committee for Food Sovereignty (IPC)\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/#\\\/schema\\\/person\\\/2022da6fc0f89b23596d0a63d82b61e1\",\"name\":\"ipc_staging\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g\",\"caption\":\"ipc_staging\"},\"sameAs\":[\"http:\\\/\\\/_\"],\"url\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/author\\\/ipc_staging\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le 2\u00b0 webinaire ouvert aux parties prenantes de la CDB : \"Transition durable de l'agriculture et des syst\u00e8mes alimentaires : liens avec le Cadre mondial pour la biodiversit\u00e9 post-2020\". - International Planning Committee for Food Sovereignty (IPC)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.foodsovereignty.org\/fr\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\/","og_locale":"fr_FR","og_type":"article","og_title":"Le 2\u00b0 webinaire ouvert aux parties prenantes de la CDB : \"Transition durable de l'agriculture et des syst\u00e8mes alimentaires : liens avec le Cadre mondial pour la biodiversit\u00e9 post-2020\". - International Planning Committee for Food Sovereignty (IPC)","og_description":"[vc_row][vc_column][vc_column_text]Le mardi 23 mars 2021, le deuxi\u00e8me webinaire ouvert aux parties prenantes organis\u00e9 par la Convention sur la biodiversit\u00e9 (CBD) s&rsquo;est tenu afin d&rsquo;explorer et d&rsquo;identifier les concepts et les questions cl\u00e9s li\u00e9s \u00e0 l&rsquo;\u00e9laboration du Cadre mondial pour la biodiversit\u00e9 post-2020. Le webinaire \u00e9tait ax\u00e9 sur \u00ab\u00a0l&rsquo;agriculture durable et la transition des syst\u00e8mes alimentaires [&hellip;]","og_url":"https:\/\/www.foodsovereignty.org\/fr\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\/","og_site_name":"International Planning Committee for Food Sovereignty (IPC)","article_published_time":"2021-03-24T10:23:23+00:00","article_modified_time":"2024-01-30T22:58:02+00:00","og_image":[{"width":2000,"height":1125,"url":"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/copertina-eng-1-1.jpg","type":"image\/jpeg"}],"author":"ipc_staging","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"ipc_staging","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.foodsovereignty.org\/fr\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\/#article","isPartOf":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\/"},"author":{"name":"ipc_staging","@id":"https:\/\/www.foodsovereignty.org\/fr\/#\/schema\/person\/2022da6fc0f89b23596d0a63d82b61e1"},"headline":"Le 2\u00b0 webinaire ouvert aux parties prenantes de la CDB : \u00ab\u00a0Transition durable de l&rsquo;agriculture et des syst\u00e8mes alimentaires : liens avec le Cadre mondial pour la biodiversit\u00e9 post-2020\u00a0\u00bb.","datePublished":"2021-03-24T10:23:23+00:00","dateModified":"2024-01-30T22:58:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\/"},"wordCount":264,"image":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/copertina-eng-1-1.jpg","articleSection":["Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.foodsovereignty.org\/fr\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\/","url":"https:\/\/www.foodsovereignty.org\/fr\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\/","name":"Le 2\u00b0 webinaire ouvert aux parties prenantes de la CDB : \"Transition durable de l'agriculture et des syst\u00e8mes alimentaires : liens avec le Cadre mondial pour la biodiversit\u00e9 post-2020\". - International Planning Committee for Food Sovereignty (IPC)","isPartOf":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\/#primaryimage"},"image":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/copertina-eng-1-1.jpg","datePublished":"2021-03-24T10:23:23+00:00","dateModified":"2024-01-30T22:58:02+00:00","author":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/#\/schema\/person\/2022da6fc0f89b23596d0a63d82b61e1"},"breadcrumb":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.foodsovereignty.org\/fr\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.foodsovereignty.org\/fr\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\/#primaryimage","url":"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/copertina-eng-1-1.jpg","contentUrl":"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/copertina-eng-1-1.jpg","width":2000,"height":1125},{"@type":"BreadcrumbList","@id":"https:\/\/www.foodsovereignty.org\/fr\/le-2-webinaire-ouvert-aux-parties-prenantes-de-la-cdb-transition-durable-de-lagriculture-et-des-systemes-alimentaires-liens-avec-le-cadre-mondial-pour-la-biodiversite-post-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.foodsovereignty.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Le 2\u00b0 webinaire ouvert aux parties prenantes de la CDB : &#8220;Transition durable de l&#8217;agriculture et des syst\u00e8mes alimentaires : liens avec le Cadre mondial pour la biodiversit\u00e9 post-2020&#8221;."}]},{"@type":"WebSite","@id":"https:\/\/www.foodsovereignty.org\/fr\/#website","url":"https:\/\/www.foodsovereignty.org\/fr\/","name":"International Planning Committee for Food Sovereignty (IPC)","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.foodsovereignty.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.foodsovereignty.org\/fr\/#\/schema\/person\/2022da6fc0f89b23596d0a63d82b61e1","name":"ipc_staging","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g","caption":"ipc_staging"},"sameAs":["http:\/\/_"],"url":"https:\/\/www.foodsovereignty.org\/fr\/author\/ipc_staging\/"}]}},"_links":{"self":[{"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/posts\/1731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/comments?post=1731"}],"version-history":[{"count":1,"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/posts\/1731\/revisions"}],"predecessor-version":[{"id":2605,"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/posts\/1731\/revisions\/2605"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/media\/2308"}],"wp:attachment":[{"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/media?parent=1731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/categories?post=1731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/tags?post=1731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}