{"id":1748,"date":"2021-09-15T16:25:08","date_gmt":"2021-09-15T16:25:08","guid":{"rendered":"https:\/\/www.foodsovereignty.org\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\/"},"modified":"2024-01-30T22:58:31","modified_gmt":"2024-01-30T22:58:31","slug":"declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19","status":"publish","type":"post","link":"https:\/\/www.foodsovereignty.org\/fr\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\/","title":{"rendered":"D\u00e9claration du Groupe de travail sur la P\u00eache du CIP sur le COVID-19"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Les communaut\u00e9s de p\u00eacheurs artisanaux, comme les autres petits producteurs d&rsquo;aliments, ont \u00e9t\u00e9 particuli\u00e8rement touch\u00e9es par la pand\u00e9mie de COVID-19. Les impacts ne se sont pas limit\u00e9s \u00e0 une question purement sanitaire &#8211; qui a, quant \u00e0 elle, mis en \u00e9vidence le manque d&rsquo;infrastructures ad\u00e9quates. Les mesures de confinement mises en place dans plusieurs pays ont exacerb\u00e9 la privation des moyens de subsistance et de la vie socioculturelle de nombreuses communaut\u00e9s. Un secteur si crucial pour les \u00e9conomies locales et l&rsquo;accessibilit\u00e9 \u00e0 des r\u00e9gimes alimentaires sains, riches en prot\u00e9ines et culturellement appropri\u00e9s a ainsi \u00e9t\u00e9 mis \u00e0 genoux. D\u00e9j\u00e0 si peu reconnue et prot\u00e9g\u00e9e, la p\u00eache artisanale est aujourd&rsquo;hui plus que jamais consid\u00e9r\u00e9e comme une opportunit\u00e9 potentielle pour la sp\u00e9culation pour la propri\u00e9t\u00e9 priv\u00e9e, l&rsquo;industrialisation et le tourisme de masse, acc\u00e9l\u00e9rant la crise environnementale avec des effets catastrophiques tels que l&rsquo;\u00e9l\u00e9vation du niveau des mers, le r\u00e9chauffement, l&rsquo;acidification et la pollution des eaux.  Il semble d\u00e9sormais de plus en plus \u00e9vident que cette situation ne peut plus \u00eatre consid\u00e9r\u00e9e comme une crise temporaire, mais qu&rsquo;un changement structurel est en train de se produire de mani\u00e8re irr\u00e9versible. N\u00e9anmoins, m\u00eame si l&rsquo;arriv\u00e9e de COVID-19 \u00e0 l&rsquo;\u00e9chelle mondiale a mis en \u00e9vidence les limites et les injustices du paradigme politique et \u00e9conomique actuel, les solutions mises en place par les autorit\u00e9s locales, les gouvernements nationaux et les organisations internationales semblent uniquement destin\u00e9es \u00e0 sauvegarder un syst\u00e8me \u00e9conomique pr\u00eat \u00e0 s&rsquo;effondrer sur lui-m\u00eame. Cette crise, notamment dans ses r\u00e9percussions politiques et \u00e9conomiques, laisse place \u00e0 la p\u00e9n\u00e9tration d&rsquo;int\u00e9r\u00eats priv\u00e9s motiv\u00e9s principalement par le profit dans les espaces politiques.  L&rsquo;importance de la p\u00eache artisanale a \u00e9t\u00e9 reconnue par les Nations Unies \u00e0 de nombreuses reprises, avec plusieurs instruments et programmes internationaux qui ont \u00e9t\u00e9 d\u00e9velopp\u00e9s pour prot\u00e9ger et promouvoir les droits de l&rsquo;homme, les peuples indig\u00e8nes, les petits producteurs alimentaires et la p\u00eache artisanale. Cependant, en raison de la nature volontaire de nombre d&rsquo;entre eux, leur contenu est trop souvent n\u00e9glig\u00e9es, tandis que les programmes et les espaces politiques \u00e9tablis pour mettre en \u00e9vidence le r\u00f4le essentiel des syst\u00e8mes alimentaires \u00e0 petite \u00e9chelle comme seule option pour nourrir le monde de mani\u00e8re saine et \u00e9cologiquement responsable sont occup\u00e9s et coopt\u00e9s par des int\u00e9r\u00eats priv\u00e9s.  Des processus tels que l&rsquo;Ann\u00e9e internationale de la p\u00eache et de l&rsquo;aquaculture artisanales de 2022 (IYAFA 2022) et la D\u00e9cennie des Nations unies pour l&rsquo;agriculture familiale (UNDFF) sont des occasions uniques de s&rsquo;attaquer \u00e0 la crise actuelle, et l&rsquo;espace de premier plan accord\u00e9 \u00e0 la soci\u00e9t\u00e9 civile doit \u00eatre soulign\u00e9 et d\u00e9fendu.  Pour ces raisons, le Groupe de travail sur la P\u00eache du Comit\u00e9 international de planification pour la souverainet\u00e9 alimentaire demande que : <\/p>\n<blockquote><p><strong>Nos communaut\u00e9s ont plus que jamais besoin de la reconnaissance institutionnelle de leur contribution \u00e0 nos soci\u00e9t\u00e9s ;<\/strong>  <strong>Nos gouvernements, avec le soutien des agences de l&rsquo;ONU, mettent en place toutes les mesures n\u00e9cessaires pour adapter les politiques nationales aux dispositions des Directives volontaires visant \u00e0 assurer la durabilit\u00e9 de la p\u00eache artisanale dans le contexte de la s\u00e9curit\u00e9 alimentaire et de l&rsquo;\u00e9radication de la pauvret\u00e9 (Directives PA) et les mettent en \u0153uvre par le biais d&rsquo;une approche participative et bas\u00e9e sur les droits de l&rsquo;homme.<\/strong><\/p><\/blockquote>\n<p> [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00a0\u00bb1\/4&Prime;][vc_single_image image=\u00a0\u00bb21773&Prime; alignment=\u00a0\u00bbcenter\u00a0\u00bb onclick=\u00a0\u00bbcustom_link\u00a0\u00bb img_link_target=\u00a0\u00bb_blank\u00a0\u00bb link=\u00a0\u00bbhttp:\/\/www.worldfisher-forum.org\/\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/4&Prime;][vc_single_image image=\u00a0\u00bb5028&Prime; alignment=\u00a0\u00bbcenter\u00a0\u00bb onclick=\u00a0\u00bbcustom_link\u00a0\u00bb img_link_target=\u00a0\u00bb_blank\u00a0\u00bb link=\u00a0\u00bbhttps:\/\/worldfishers.org\/\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/4&Prime;][vc_single_image image=\u00a0\u00bb5044&Prime; alignment=\u00a0\u00bbcenter\u00a0\u00bb onclick=\u00a0\u00bbcustom_link\u00a0\u00bb link=\u00a0\u00bbhttps:\/\/www.iitc.org\/\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb1\/4&Prime;][vc_single_image image=\u00a0\u00bb5047&Prime; alignment=\u00a0\u00bbcenter\u00a0\u00bb onclick=\u00a0\u00bbcustom_link\u00a0\u00bb link=\u00a0\u00bbhttps:\/\/viacampesina.org\/fr\/\u00a0\u00bb][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Les communaut\u00e9s de p\u00eacheurs artisanaux, comme les autres petits producteurs d&rsquo;aliments, ont \u00e9t\u00e9 particuli\u00e8rement touch\u00e9es par la pand\u00e9mie de COVID-19. Les impacts ne se sont pas limit\u00e9s \u00e0 une question purement sanitaire &#8211; qui a, quant \u00e0 elle, mis en \u00e9vidence le manque d&rsquo;infrastructures ad\u00e9quates. Les mesures de confinement mises en place dans plusieurs pays [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2356,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[57],"tags":[],"class_list":["post-1748","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","regional_processes_tax-africa","regional_processes_tax-asia-pacific","regional_processes_tax-europe-central-asia","regional_processes_tax-latin-america-caribbean","regional_processes_tax-near-east-north-africa","working_groups_tax-fisheries"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9claration du Groupe de travail sur la P\u00eache du CIP sur le COVID-19 - International Planning Committee for Food Sovereignty (IPC)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.foodsovereignty.org\/fr\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9claration du Groupe de travail sur la P\u00eache du CIP sur le COVID-19 - International Planning Committee for Food Sovereignty (IPC)\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text]Les communaut\u00e9s de p\u00eacheurs artisanaux, comme les autres petits producteurs d&rsquo;aliments, ont \u00e9t\u00e9 particuli\u00e8rement touch\u00e9es par la pand\u00e9mie de COVID-19. Les impacts ne se sont pas limit\u00e9s \u00e0 une question purement sanitaire &#8211; qui a, quant \u00e0 elle, mis en \u00e9vidence le manque d&rsquo;infrastructures ad\u00e9quates. Les mesures de confinement mises en place dans plusieurs pays [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.foodsovereignty.org\/fr\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"International Planning Committee for Food Sovereignty (IPC)\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-15T16:25:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-30T22:58:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/Fisheries_Covid_Statement_EN.png\" \/>\n\t<meta property=\"og:image:width\" content=\"3000\" \/>\n\t<meta property=\"og:image:height\" content=\"1055\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ipc_staging\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ipc_staging\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\\\/\"},\"author\":{\"name\":\"ipc_staging\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/#\\\/schema\\\/person\\\/2022da6fc0f89b23596d0a63d82b61e1\"},\"headline\":\"D\u00e9claration du Groupe de travail sur la P\u00eache du CIP sur le COVID-19\",\"datePublished\":\"2021-09-15T16:25:08+00:00\",\"dateModified\":\"2024-01-30T22:58:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\\\/\"},\"wordCount\":724,\"image\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.foodsovereignty.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Fisheries_Covid_Statement_EN.png\",\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\\\/\",\"url\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\\\/\",\"name\":\"D\u00e9claration du Groupe de travail sur la P\u00eache du CIP sur le COVID-19 - International Planning Committee for Food Sovereignty (IPC)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.foodsovereignty.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Fisheries_Covid_Statement_EN.png\",\"datePublished\":\"2021-09-15T16:25:08+00:00\",\"dateModified\":\"2024-01-30T22:58:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/#\\\/schema\\\/person\\\/2022da6fc0f89b23596d0a63d82b61e1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.foodsovereignty.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Fisheries_Covid_Statement_EN.png\",\"contentUrl\":\"https:\\\/\\\/www.foodsovereignty.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Fisheries_Covid_Statement_EN.png\",\"width\":3000,\"height\":1055},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9claration du Groupe de travail sur la P\u00eache du CIP sur le COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/\",\"name\":\"International Planning Committee for Food Sovereignty (IPC)\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/#\\\/schema\\\/person\\\/2022da6fc0f89b23596d0a63d82b61e1\",\"name\":\"ipc_staging\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g\",\"caption\":\"ipc_staging\"},\"sameAs\":[\"http:\\\/\\\/_\"],\"url\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/author\\\/ipc_staging\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9claration du Groupe de travail sur la P\u00eache du CIP sur le COVID-19 - International Planning Committee for Food Sovereignty (IPC)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.foodsovereignty.org\/fr\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9claration du Groupe de travail sur la P\u00eache du CIP sur le COVID-19 - International Planning Committee for Food Sovereignty (IPC)","og_description":"[vc_row][vc_column][vc_column_text]Les communaut\u00e9s de p\u00eacheurs artisanaux, comme les autres petits producteurs d&rsquo;aliments, ont \u00e9t\u00e9 particuli\u00e8rement touch\u00e9es par la pand\u00e9mie de COVID-19. Les impacts ne se sont pas limit\u00e9s \u00e0 une question purement sanitaire &#8211; qui a, quant \u00e0 elle, mis en \u00e9vidence le manque d&rsquo;infrastructures ad\u00e9quates. Les mesures de confinement mises en place dans plusieurs pays [&hellip;]","og_url":"https:\/\/www.foodsovereignty.org\/fr\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\/","og_site_name":"International Planning Committee for Food Sovereignty (IPC)","article_published_time":"2021-09-15T16:25:08+00:00","article_modified_time":"2024-01-30T22:58:31+00:00","og_image":[{"width":3000,"height":1055,"url":"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/Fisheries_Covid_Statement_EN.png","type":"image\/png"}],"author":"ipc_staging","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"ipc_staging","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.foodsovereignty.org\/fr\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\/#article","isPartOf":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\/"},"author":{"name":"ipc_staging","@id":"https:\/\/www.foodsovereignty.org\/fr\/#\/schema\/person\/2022da6fc0f89b23596d0a63d82b61e1"},"headline":"D\u00e9claration du Groupe de travail sur la P\u00eache du CIP sur le COVID-19","datePublished":"2021-09-15T16:25:08+00:00","dateModified":"2024-01-30T22:58:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\/"},"wordCount":724,"image":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/Fisheries_Covid_Statement_EN.png","articleSection":["Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.foodsovereignty.org\/fr\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\/","url":"https:\/\/www.foodsovereignty.org\/fr\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\/","name":"D\u00e9claration du Groupe de travail sur la P\u00eache du CIP sur le COVID-19 - International Planning Committee for Food Sovereignty (IPC)","isPartOf":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/Fisheries_Covid_Statement_EN.png","datePublished":"2021-09-15T16:25:08+00:00","dateModified":"2024-01-30T22:58:31+00:00","author":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/#\/schema\/person\/2022da6fc0f89b23596d0a63d82b61e1"},"breadcrumb":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.foodsovereignty.org\/fr\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.foodsovereignty.org\/fr\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\/#primaryimage","url":"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/Fisheries_Covid_Statement_EN.png","contentUrl":"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/Fisheries_Covid_Statement_EN.png","width":3000,"height":1055},{"@type":"BreadcrumbList","@id":"https:\/\/www.foodsovereignty.org\/fr\/declaration-du-groupe-de-travail-sur-la-peche-du-cip-sur-le-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.foodsovereignty.org\/fr\/"},{"@type":"ListItem","position":2,"name":"D\u00e9claration du Groupe de travail sur la P\u00eache du CIP sur le COVID-19"}]},{"@type":"WebSite","@id":"https:\/\/www.foodsovereignty.org\/fr\/#website","url":"https:\/\/www.foodsovereignty.org\/fr\/","name":"International Planning Committee for Food Sovereignty (IPC)","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.foodsovereignty.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.foodsovereignty.org\/fr\/#\/schema\/person\/2022da6fc0f89b23596d0a63d82b61e1","name":"ipc_staging","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g","caption":"ipc_staging"},"sameAs":["http:\/\/_"],"url":"https:\/\/www.foodsovereignty.org\/fr\/author\/ipc_staging\/"}]}},"_links":{"self":[{"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/posts\/1748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/comments?post=1748"}],"version-history":[{"count":1,"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/posts\/1748\/revisions"}],"predecessor-version":[{"id":2637,"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/posts\/1748\/revisions\/2637"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/media\/2356"}],"wp:attachment":[{"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/media?parent=1748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/categories?post=1748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/tags?post=1748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}