{"id":1764,"date":"2021-11-21T11:20:05","date_gmt":"2021-11-21T11:20:05","guid":{"rendered":"https:\/\/www.foodsovereignty.org\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\/"},"modified":"2024-01-30T22:58:34","modified_gmt":"2024-01-30T22:58:34","slug":"21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip","status":"publish","type":"post","link":"https:\/\/www.foodsovereignty.org\/fr\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\/","title":{"rendered":"21 novembre; Journ\u00e9e mondiale de la p\u00eache &#8211; D\u00e9claration de la CIP"},"content":{"rendered":"<p><em><strong>Aujourd&rsquo;hui, 21 novembre, c&rsquo;est la Journ\u00e9e internationale de la p\u00eache. Nous profitons de cette occasion pour publier la d\u00e9claration de la CIP.<\/strong><\/em>  <span style=\"font-weight: 400;\">Au sein du Comit\u00e9 International de Planification pour la Souverainet\u00e9 Alimentaire (IPC), nous repr\u00e9sentons les p\u00eacheurs \u00e0 petite \u00e9chelle, y compris les peuples autochtones des quatre mouvements mondiaux, le Forum Mondial des P\u00eacheurs et des Travailleurs de la P\u00eache (WFF), le Forum Mondial des Peuples de P\u00eacheurs (WFFP), le Conseil International des Trait\u00e9s Indiens (CITI) et La Via Campesina (LVC). Nos membres proviennent du monde entier et des communaut\u00e9s de p\u00eache c\u00f4ti\u00e8res et int\u00e9rieures.\u00a0<\/span>  &nbsp;  <span style=\"font-weight: 400;\">Aujourd&rsquo;hui, nous rappelons que la Journ\u00e9e mondiale de la p\u00eache (WFD) est porteuse de notre riche histoire et a \u00e9t\u00e9 c\u00e9l\u00e9br\u00e9e pour la premi\u00e8re fois lorsque nous avons form\u00e9 les mouvements mondiaux de p\u00eacheurs (WFFP\/WFF) \u00e0 Delhi en 1997. \u00c0 l&rsquo;\u00e9poque, nous d\u00e9noncions la p\u00eache industrielle et l&rsquo;aquaculture parce que ces deux secteurs entra\u00eenent la destruction de l&rsquo;environnement et l&rsquo;expropriation des communaut\u00e9s de p\u00eacheurs, et nous avons d\u00e9cid\u00e9 que ce jour de notre naissance, la Journ\u00e9e mondiale de la p\u00eache, serait une journ\u00e9e de c\u00e9l\u00e9bration internationale de la p\u00eache de capture \u00e0 petite \u00e9chelle. Nous avons d\u00e9cid\u00e9 que ce jour de notre naissance, la Journ\u00e9e mondiale de la p\u00eache, serait une journ\u00e9e de c\u00e9l\u00e9bration de la p\u00eache de capture artisanal \u00e0 l&rsquo;\u00e9chelle internationale. C&rsquo;est une journ\u00e9e qui t\u00e9moigne de la d\u00e9termination et des efforts des p\u00eacheurs pour contribuer fi\u00e8rement aux syst\u00e8mes alimentaires mondiaux et \u00e0 une soci\u00e9t\u00e9 humaine en g\u00e9n\u00e9ral. <\/span>  <strong>Lire la d\u00e9claration <a href=\"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2021\/11\/Journ\u00e9e-mondiale-de-la-p\u00eache-D\u00e9claration-1.pdf\">ici<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aujourd&rsquo;hui, 21 novembre, c&rsquo;est la Journ\u00e9e internationale de la p\u00eache. Nous profitons de cette occasion pour publier la d\u00e9claration de la CIP. Au sein du Comit\u00e9 International de Planification pour la Souverainet\u00e9 Alimentaire (IPC), nous repr\u00e9sentons les p\u00eacheurs \u00e0 petite \u00e9chelle, y compris les peuples autochtones des quatre mouvements mondiaux, le Forum Mondial des P\u00eacheurs [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2379,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[57],"tags":[85],"class_list":["post-1764","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","tag-food-sovereignty","regional_processes_tax-africa","regional_processes_tax-asia-pacific","regional_processes_tax-europe-central-asia","regional_processes_tax-latin-america-caribbean","regional_processes_tax-near-east-north-africa","working_groups_tax-fisheries"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>21 novembre; Journ\u00e9e mondiale de la p\u00eache - D\u00e9claration de la CIP - International Planning Committee for Food Sovereignty (IPC)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.foodsovereignty.org\/fr\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"21 novembre; Journ\u00e9e mondiale de la p\u00eache - D\u00e9claration de la CIP - International Planning Committee for Food Sovereignty (IPC)\" \/>\n<meta property=\"og:description\" content=\"Aujourd&rsquo;hui, 21 novembre, c&rsquo;est la Journ\u00e9e internationale de la p\u00eache. Nous profitons de cette occasion pour publier la d\u00e9claration de la CIP. Au sein du Comit\u00e9 International de Planification pour la Souverainet\u00e9 Alimentaire (IPC), nous repr\u00e9sentons les p\u00eacheurs \u00e0 petite \u00e9chelle, y compris les peuples autochtones des quatre mouvements mondiaux, le Forum Mondial des P\u00eacheurs [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.foodsovereignty.org\/fr\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\/\" \/>\n<meta property=\"og:site_name\" content=\"International Planning Committee for Food Sovereignty (IPC)\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-21T11:20:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-30T22:58:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/dia-inter.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"433\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ipc_staging\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ipc_staging\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\\\/\"},\"author\":{\"name\":\"ipc_staging\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/#\\\/schema\\\/person\\\/2022da6fc0f89b23596d0a63d82b61e1\"},\"headline\":\"21 novembre; Journ\u00e9e mondiale de la p\u00eache &#8211; D\u00e9claration de la CIP\",\"datePublished\":\"2021-11-21T11:20:05+00:00\",\"dateModified\":\"2024-01-30T22:58:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\\\/\"},\"wordCount\":317,\"image\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.foodsovereignty.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/dia-inter.jpg\",\"keywords\":[\"food sovereignty\"],\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\\\/\",\"url\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\\\/\",\"name\":\"21 novembre; Journ\u00e9e mondiale de la p\u00eache - D\u00e9claration de la CIP - International Planning Committee for Food Sovereignty (IPC)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.foodsovereignty.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/dia-inter.jpg\",\"datePublished\":\"2021-11-21T11:20:05+00:00\",\"dateModified\":\"2024-01-30T22:58:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/#\\\/schema\\\/person\\\/2022da6fc0f89b23596d0a63d82b61e1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.foodsovereignty.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/dia-inter.jpg\",\"contentUrl\":\"https:\\\/\\\/www.foodsovereignty.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/dia-inter.jpg\",\"width\":650,\"height\":433},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"21 novembre; Journ\u00e9e mondiale de la p\u00eache &#8211; D\u00e9claration de la CIP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/\",\"name\":\"International Planning Committee for Food Sovereignty (IPC)\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/#\\\/schema\\\/person\\\/2022da6fc0f89b23596d0a63d82b61e1\",\"name\":\"ipc_staging\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g\",\"caption\":\"ipc_staging\"},\"sameAs\":[\"http:\\\/\\\/_\"],\"url\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/author\\\/ipc_staging\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"21 novembre; Journ\u00e9e mondiale de la p\u00eache - D\u00e9claration de la CIP - International Planning Committee for Food Sovereignty (IPC)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.foodsovereignty.org\/fr\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\/","og_locale":"fr_FR","og_type":"article","og_title":"21 novembre; Journ\u00e9e mondiale de la p\u00eache - D\u00e9claration de la CIP - International Planning Committee for Food Sovereignty (IPC)","og_description":"Aujourd&rsquo;hui, 21 novembre, c&rsquo;est la Journ\u00e9e internationale de la p\u00eache. Nous profitons de cette occasion pour publier la d\u00e9claration de la CIP. Au sein du Comit\u00e9 International de Planification pour la Souverainet\u00e9 Alimentaire (IPC), nous repr\u00e9sentons les p\u00eacheurs \u00e0 petite \u00e9chelle, y compris les peuples autochtones des quatre mouvements mondiaux, le Forum Mondial des P\u00eacheurs [&hellip;]","og_url":"https:\/\/www.foodsovereignty.org\/fr\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\/","og_site_name":"International Planning Committee for Food Sovereignty (IPC)","article_published_time":"2021-11-21T11:20:05+00:00","article_modified_time":"2024-01-30T22:58:34+00:00","og_image":[{"width":650,"height":433,"url":"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/dia-inter.jpg","type":"image\/jpeg"}],"author":"ipc_staging","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"ipc_staging","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.foodsovereignty.org\/fr\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\/#article","isPartOf":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\/"},"author":{"name":"ipc_staging","@id":"https:\/\/www.foodsovereignty.org\/fr\/#\/schema\/person\/2022da6fc0f89b23596d0a63d82b61e1"},"headline":"21 novembre; Journ\u00e9e mondiale de la p\u00eache &#8211; D\u00e9claration de la CIP","datePublished":"2021-11-21T11:20:05+00:00","dateModified":"2024-01-30T22:58:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\/"},"wordCount":317,"image":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\/#primaryimage"},"thumbnailUrl":"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/dia-inter.jpg","keywords":["food sovereignty"],"articleSection":["Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.foodsovereignty.org\/fr\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\/","url":"https:\/\/www.foodsovereignty.org\/fr\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\/","name":"21 novembre; Journ\u00e9e mondiale de la p\u00eache - D\u00e9claration de la CIP - International Planning Committee for Food Sovereignty (IPC)","isPartOf":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\/#primaryimage"},"image":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\/#primaryimage"},"thumbnailUrl":"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/dia-inter.jpg","datePublished":"2021-11-21T11:20:05+00:00","dateModified":"2024-01-30T22:58:34+00:00","author":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/#\/schema\/person\/2022da6fc0f89b23596d0a63d82b61e1"},"breadcrumb":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.foodsovereignty.org\/fr\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.foodsovereignty.org\/fr\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\/#primaryimage","url":"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/dia-inter.jpg","contentUrl":"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/dia-inter.jpg","width":650,"height":433},{"@type":"BreadcrumbList","@id":"https:\/\/www.foodsovereignty.org\/fr\/21-novembre-journee-mondiale-de-la-peche-declaration-de-la-cip\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.foodsovereignty.org\/fr\/"},{"@type":"ListItem","position":2,"name":"21 novembre; Journ\u00e9e mondiale de la p\u00eache &#8211; D\u00e9claration de la CIP"}]},{"@type":"WebSite","@id":"https:\/\/www.foodsovereignty.org\/fr\/#website","url":"https:\/\/www.foodsovereignty.org\/fr\/","name":"International Planning Committee for Food Sovereignty (IPC)","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.foodsovereignty.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.foodsovereignty.org\/fr\/#\/schema\/person\/2022da6fc0f89b23596d0a63d82b61e1","name":"ipc_staging","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g","caption":"ipc_staging"},"sameAs":["http:\/\/_"],"url":"https:\/\/www.foodsovereignty.org\/fr\/author\/ipc_staging\/"}]}},"_links":{"self":[{"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/posts\/1764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/comments?post=1764"}],"version-history":[{"count":1,"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/posts\/1764\/revisions"}],"predecessor-version":[{"id":2641,"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/posts\/1764\/revisions\/2641"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/media\/2379"}],"wp:attachment":[{"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/media?parent=1764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/categories?post=1764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/tags?post=1764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}