{"id":1810,"date":"2024-01-25T22:19:37","date_gmt":"2024-01-25T22:19:37","guid":{"rendered":"https:\/\/www.foodsovereignty.org\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\/"},"modified":"2024-02-14T15:10:15","modified_gmt":"2024-02-14T15:10:15","slug":"les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi","status":"publish","type":"post","link":"https:\/\/www.foodsovereignty.org\/fr\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\/","title":{"rendered":"Les petits p\u00eacheurs n\u00e9glig\u00e9s lors de la premi\u00e8re r\u00e9union du sous-comit\u00e9 du COFI"},"content":{"rendered":"<p>La session inaugurale du Sous-Comit\u00e9 sur la Gestion des P\u00eaches s&rsquo;est d\u00e9roul\u00e9e virtuellement du 15 au 18 janvier 2024. \u00c9tabli en 2022 par le Comit\u00e9 des p\u00eaches (COFI) de l&rsquo;Organisation des Nations Unies pour l&rsquo;alimentation et l&rsquo;agriculture (FAO), ce sous-comit\u00e9 a \u00e9t\u00e9 cr\u00e9\u00e9 pour faciliter des discussions approfondies sur la gestion des p\u00eaches, en accordant une attention particuli\u00e8re aux <strong>p\u00eaches \u00e0 petite \u00e9chelle<\/strong> (PPE). D\u00e8s le d\u00e9but, le <strong>Comit\u00e9 international de planification pour la souverainet\u00e9 alimentaire<\/strong> (CIP) s&rsquo;est oppos\u00e9 au Sous-Comit\u00e9, comme indiqu\u00e9 dans la d\u00e9claration du COFI 35: \u00ab\u00a0Nous exprimons notre inqui\u00e9tude selon laquelle un tel sous-comit\u00e9 pourrait ne pas aborder de mani\u00e8re ad\u00e9quate les probl\u00e8mes globaux li\u00e9s \u00e0 la p\u00eache \u00e0 petite \u00e9chelle, qui vont au-del\u00e0 de la simple gestion pour englober des aspects plus larges tels que le d\u00e9veloppement social, les droits de l&rsquo;homme et les droits de propri\u00e9t\u00e9 dans les p\u00eaches maritimes et int\u00e9rieures.\u00a0\u00bb Sous la pr\u00e9sidence de M. Stefa\u0301n A\u0301smundsson, les premi\u00e8res sessions du Sous-Comit\u00e9 ont diff\u00e9r\u00e9 consid\u00e9rablement de l&rsquo;exp\u00e9rience lors du dernier COFI 35, o\u00f9 des contraintes strictes de temps \u00e9taient impos\u00e9es aux observateurs, allant jusqu&rsquo;\u00e0 leur exclusion en raison des limitations temporelles. En revanche, le pr\u00e9sident du Sous-Comit\u00e9, dans ce cas, permet efficacement aux observateurs d&rsquo;exprimer leurs opinions. Bien que la premi\u00e8re session du Sous-Comit\u00e9 se soit d\u00e9roul\u00e9e sans heurts, les discussions ult\u00e9rieures ont valid\u00e9 les pr\u00e9occupations du CIP. Les d\u00e9clarations des gouvernements ont mis disproportionnellement l&rsquo;accent sur la gestion des p\u00eaches, se concentrant sur les d\u00e9fis financiers, techniques et institutionnels. Cette focalisation \u00e9troite a n\u00e9glig\u00e9 la nature holistique des p\u00eaches \u00e0 petite \u00e9chelle, \u00e9troitement li\u00e9e \u00e0 un mode de vie, \u00e0 un patrimoine culturel et aux moyens de subsistance des communaut\u00e9s c\u00f4ti\u00e8res et int\u00e9rieures. Reconna\u00eetre cette perspective plus large est essentiel pour soutenir la vie, garantir les droits fondamentaux de l&rsquo;homme et assurer la s\u00e9curit\u00e9 alimentaire de millions de personnes. L&rsquo;ordre du jour comprenait des discussions sur les points suivants:<\/p>\n<ul>\n<li>Pratiques actuelles de gestion des p\u00eaches avec une attention particuli\u00e8re pour la p\u00eache \u00e0 petite \u00e9chelle (Point 2)<\/li>\n<li>P\u00eache ill\u00e9gale, non d\u00e9clar\u00e9e et non r\u00e9glement\u00e9e (INN) dans le contexte d&rsquo;une gestion efficace des p\u00eaches (Point 3)<\/li>\n<li>Int\u00e9gration de la biodiversit\u00e9 dans la gestion des p\u00eaches (Point 4)<\/li>\n<li>Changement climatique et gestion des p\u00eaches (Point 5)<\/li>\n<\/ul>\n<p>En g\u00e9n\u00e9ral, seulement quelques gouvernements ont reconnu et r\u00e9f\u00e9renc\u00e9 les lignes directrices sur la p\u00eache \u00e0 petite \u00e9chelle (SSF), soulignant l&rsquo;imp\u00e9ratif de plaider en faveur de leur mise en \u0153uvre. Sans surprise, aucune mention n&rsquo;a \u00e9t\u00e9 faite du 10e anniversaire des lignes directrices sur les PPE, et une discussion centr\u00e9e sur les personnes, pla\u00e7ant les PPE au centre et s&rsquo;appuyant sur une approche ascendante, \u00e9tait notablement absente. En ce qui concerne l&rsquo;\u00e9l\u00e9ment crucial de l&rsquo;ordre du jour n\u00b02, ax\u00e9 sur les pratiques actuelles de gestion des p\u00eaches avec un accent sur la p\u00eaches artisanale, les lignes directrices sur les PPE \u00e9taient impliqu\u00e9es, bien que avec une mise en garde sur le potentiel de duplication et de conflits avec les lignes directrices sur la gestion des p\u00eaches en cours d&rsquo;\u00e9laboration par la FAO. Certaines d\u00e9l\u00e9gations ont soulign\u00e9 la n\u00e9cessit\u00e9 de <strong>mieux clarifier ce que l&rsquo;on entend par p\u00eache \u00e0 petite \u00e9chelle et ce qui ne l&rsquo;est pas<\/strong>. En abordant le point 3, centr\u00e9 sur la <strong>p\u00eache ill\u00e9gale, non d\u00e9clar\u00e9e et non r\u00e9glement\u00e9e<\/strong> (INN), le discours est revenu \u00e0 une dimension plus technique et statistique. Les d\u00e9l\u00e9gations gouvernementales ont salu\u00e9 la publication par la FAO de lignes directrices techniques sur les m\u00e9thodologies et les indicateurs pour \u00e9valuer l&rsquo;\u00e9tendue et l&rsquo;impact de la p\u00eache INN. Les gouvernements ont appel\u00e9 \u00e0 un soutien accru de la FAO dans des domaines tels que l&rsquo;Accord sur les mesures du ressort de l&rsquo;\u00c9tat du port (PSMA), les syst\u00e8mes du Marine Stewardship Council (MSC) et la collecte et l&rsquo;analyse de donn\u00e9es pour faciliter l&rsquo;\u00e9change d&rsquo;informations. De mani\u00e8re frappante, peu de participants ont soulign\u00e9 le r\u00f4le potentiel des p\u00eaches \u00e0 petite \u00e9chelle dans la lutte contre la p\u00eache INN, un point soulign\u00e9 par le CIP dans sa d\u00e9claration. Comme cela s&rsquo;est produit lors du COFI35, le risque potentiel d&rsquo;inclure certains types de PPE dans la p\u00eache INN n&rsquo;a pas \u00e9t\u00e9 pris en compte par les gouvernements. Cela a suscit\u00e9 des inqui\u00e9tudes pour le CIP, nous amenant \u00e0 demander la reconnaissance des droits coutumiers et fonciers et des droits collectifs des communaut\u00e9s de PPE et des PI, en l&rsquo;absence d&rsquo;une d\u00e9finition nationale des p\u00eaches \u00e0 petite \u00e9chelle. La discussion sur la biodiversit\u00e9 au sein du Sous-Comit\u00e9 \u00e9tait \u00e9troitement li\u00e9e au Cadre de r\u00e9f\u00e9rence mondial sur la biodiversit\u00e9 Kunming-Montr\u00e9al et \u00e0 l&rsquo;alignement avec la Strat\u00e9gie de la FAO pour l&rsquo;int\u00e9gration de la biodiversit\u00e9 dans les secteurs agricoles. Les d\u00e9l\u00e9gations gouvernementales ont r\u00e9sum\u00e9 les actions cl\u00e9s entreprises au niveau national pour sauvegarder la biodiversit\u00e9 et atteindre les objectifs du <strong>Cadre mondial de la biodiversit\u00e9<\/strong> (GBF). Certains gouvernements ont appel\u00e9 \u00e0 l&rsquo;int\u00e9gration des connaissances autochtones, traditionnelles et locales dans les plans de conservation et de protection de la biodiversit\u00e9, mais les exemples de mise en \u0153uvre au niveau national \u00e9taient limit\u00e9s. Une fois de plus, le r\u00f4le inestimable des PPE et des peuples autochtones en tant que gardiens des mers c\u00f4ti\u00e8res et des eaux int\u00e9rieures a \u00e9t\u00e9 n\u00e9glig\u00e9, aux c\u00f4t\u00e9s des effets n\u00e9fastes potentiels caus\u00e9s par les plans de conservation au niveau national, en particulier la mani\u00e8re dont l&rsquo;\u00e9conomie bleue est un facteur significatif de perte de biodiversit\u00e9 et, par cons\u00e9quent, d&rsquo;impact sur le changement climatique. La discussion conclusive portait sur le changement climatique et la gestion des p\u00eaches. Tous les gouvernements ont soulign\u00e9 l&rsquo;importance des derniers accords de la COP et ont salu\u00e9 les efforts de la FAO pour s&rsquo;aligner sur l&rsquo;agenda international du changement climatique et int\u00e9grer le changement climatique dans la gestion des p\u00eaches. <strong>Le Sous-Comit\u00e9 a reconnu la vuln\u00e9rabilit\u00e9 des p\u00eacheurs artisans et des peuples autochtones au changement climatique<\/strong>, ainsi que le r\u00f4le vital des p\u00eaches dans la fourniture de solutions climatiques, appelant \u00e0 une approche holistique pour relever ces d\u00e9fis. Mais une fois de plus, le Sous-Comit\u00e9 a manqu\u00e9 des occasions de discuter de la <strong>connexion complexe entre l&rsquo;\u00e9conomie bleue et les impacts du changement climatique<\/strong>. De plus, une occasion manqu\u00e9e a \u00e9t\u00e9 de mettre en lumi\u00e8re comment divers projets de d\u00e9veloppement posent des menaces aux habitats naturels des p\u00eaches, comme la conversion de champs agricoles fertiles et de mangroves en fermes de crevettes, ou la participation \u00e0 des activit\u00e9s mini\u00e8res dans les r\u00e9gions c\u00f4ti\u00e8res et int\u00e9rieures. &#8212; La prochaine session du Sous-Comit\u00e9 sur la Gestion des P\u00eaches aura lieu en personne en 2026. Les d\u00e9clarations de l&rsquo;IPC et d&rsquo;autres d\u00e9l\u00e9gations sont disponibles sur: <a href=\"https:\/\/www.fao.org\/cofi\/fish-management\/statements\/fr\" target=\"_blank\" rel=\"noopener\">FAO<\/a> Le rapport final du premier Sous-Comit\u00e9 sur la Gestion des P\u00eaches n&rsquo;est toujours pas disponible en ligne.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La session inaugurale du Sous-Comit\u00e9 sur la Gestion des P\u00eaches s&rsquo;est d\u00e9roul\u00e9e virtuellement du 15 au 18 janvier 2024. \u00c9tabli en 2022 par le Comit\u00e9 des p\u00eaches (COFI) de l&rsquo;Organisation des Nations Unies pour l&rsquo;alimentation et l&rsquo;agriculture (FAO), ce sous-comit\u00e9 a \u00e9t\u00e9 cr\u00e9\u00e9 pour faciliter des discussions approfondies sur la gestion des p\u00eaches, en accordant [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2509,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[57],"tags":[371,289],"class_list":["post-1810","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","tag-cofi-fr","tag-peche-a-petite-echelle","regional_processes_tax-africa","regional_processes_tax-asia-pacific","regional_processes_tax-europe-central-asia","regional_processes_tax-latin-america-caribbean","regional_processes_tax-near-east-north-africa","working_groups_tax-fisheries"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les petits p\u00eacheurs n\u00e9glig\u00e9s lors de la premi\u00e8re r\u00e9union du sous-comit\u00e9 du COFI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.foodsovereignty.org\/fr\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les petits p\u00eacheurs n\u00e9glig\u00e9s lors de la premi\u00e8re r\u00e9union du sous-comit\u00e9 du COFI\" \/>\n<meta property=\"og:description\" content=\"La session inaugurale du Sous-Comit\u00e9 sur la Gestion des P\u00eaches s&rsquo;est d\u00e9roul\u00e9e virtuellement du 15 au 18 janvier 2024. \u00c9tabli en 2022 par le Comit\u00e9 des p\u00eaches (COFI) de l&rsquo;Organisation des Nations Unies pour l&rsquo;alimentation et l&rsquo;agriculture (FAO), ce sous-comit\u00e9 a \u00e9t\u00e9 cr\u00e9\u00e9 pour faciliter des discussions approfondies sur la gestion des p\u00eaches, en accordant [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.foodsovereignty.org\/fr\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\/\" \/>\n<meta property=\"og:site_name\" content=\"International Planning Committee for Food Sovereignty (IPC)\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-25T22:19:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-14T15:10:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/SubCommittee-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ipc_staging\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ipc_staging\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\\\/\"},\"author\":{\"name\":\"ipc_staging\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/#\\\/schema\\\/person\\\/2022da6fc0f89b23596d0a63d82b61e1\"},\"headline\":\"Les petits p\u00eacheurs n\u00e9glig\u00e9s lors de la premi\u00e8re r\u00e9union du sous-comit\u00e9 du COFI\",\"datePublished\":\"2024-01-25T22:19:37+00:00\",\"dateModified\":\"2024-02-14T15:10:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\\\/\"},\"wordCount\":1283,\"image\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.foodsovereignty.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/SubCommittee-2.png\",\"keywords\":[\"COFI\",\"P\u00eache \u00e0 petite echelle\"],\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\\\/\",\"url\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\\\/\",\"name\":\"Les petits p\u00eacheurs n\u00e9glig\u00e9s lors de la premi\u00e8re r\u00e9union du sous-comit\u00e9 du COFI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.foodsovereignty.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/SubCommittee-2.png\",\"datePublished\":\"2024-01-25T22:19:37+00:00\",\"dateModified\":\"2024-02-14T15:10:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/#\\\/schema\\\/person\\\/2022da6fc0f89b23596d0a63d82b61e1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.foodsovereignty.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/SubCommittee-2.png\",\"contentUrl\":\"https:\\\/\\\/www.foodsovereignty.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/SubCommittee-2.png\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les petits p\u00eacheurs n\u00e9glig\u00e9s lors de la premi\u00e8re r\u00e9union du sous-comit\u00e9 du COFI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/\",\"name\":\"International Planning Committee for Food Sovereignty (IPC)\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/#\\\/schema\\\/person\\\/2022da6fc0f89b23596d0a63d82b61e1\",\"name\":\"ipc_staging\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g\",\"caption\":\"ipc_staging\"},\"sameAs\":[\"http:\\\/\\\/_\"],\"url\":\"https:\\\/\\\/www.foodsovereignty.org\\\/fr\\\/author\\\/ipc_staging\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les petits p\u00eacheurs n\u00e9glig\u00e9s lors de la premi\u00e8re r\u00e9union du sous-comit\u00e9 du COFI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.foodsovereignty.org\/fr\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\/","og_locale":"fr_FR","og_type":"article","og_title":"Les petits p\u00eacheurs n\u00e9glig\u00e9s lors de la premi\u00e8re r\u00e9union du sous-comit\u00e9 du COFI","og_description":"La session inaugurale du Sous-Comit\u00e9 sur la Gestion des P\u00eaches s&rsquo;est d\u00e9roul\u00e9e virtuellement du 15 au 18 janvier 2024. \u00c9tabli en 2022 par le Comit\u00e9 des p\u00eaches (COFI) de l&rsquo;Organisation des Nations Unies pour l&rsquo;alimentation et l&rsquo;agriculture (FAO), ce sous-comit\u00e9 a \u00e9t\u00e9 cr\u00e9\u00e9 pour faciliter des discussions approfondies sur la gestion des p\u00eaches, en accordant [&hellip;]","og_url":"https:\/\/www.foodsovereignty.org\/fr\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\/","og_site_name":"International Planning Committee for Food Sovereignty (IPC)","article_published_time":"2024-01-25T22:19:37+00:00","article_modified_time":"2024-02-14T15:10:15+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/SubCommittee-2.png","type":"image\/png"}],"author":"ipc_staging","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"ipc_staging","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.foodsovereignty.org\/fr\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\/#article","isPartOf":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\/"},"author":{"name":"ipc_staging","@id":"https:\/\/www.foodsovereignty.org\/fr\/#\/schema\/person\/2022da6fc0f89b23596d0a63d82b61e1"},"headline":"Les petits p\u00eacheurs n\u00e9glig\u00e9s lors de la premi\u00e8re r\u00e9union du sous-comit\u00e9 du COFI","datePublished":"2024-01-25T22:19:37+00:00","dateModified":"2024-02-14T15:10:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\/"},"wordCount":1283,"image":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/SubCommittee-2.png","keywords":["COFI","P\u00eache \u00e0 petite echelle"],"articleSection":["Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.foodsovereignty.org\/fr\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\/","url":"https:\/\/www.foodsovereignty.org\/fr\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\/","name":"Les petits p\u00eacheurs n\u00e9glig\u00e9s lors de la premi\u00e8re r\u00e9union du sous-comit\u00e9 du COFI","isPartOf":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\/#primaryimage"},"image":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/SubCommittee-2.png","datePublished":"2024-01-25T22:19:37+00:00","dateModified":"2024-02-14T15:10:15+00:00","author":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/#\/schema\/person\/2022da6fc0f89b23596d0a63d82b61e1"},"breadcrumb":{"@id":"https:\/\/www.foodsovereignty.org\/fr\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.foodsovereignty.org\/fr\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.foodsovereignty.org\/fr\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\/#primaryimage","url":"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/SubCommittee-2.png","contentUrl":"https:\/\/www.foodsovereignty.org\/wp-content\/uploads\/2024\/01\/SubCommittee-2.png","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.foodsovereignty.org\/fr\/les-petits-pecheurs-negliges-lors-de-la-premiere-reunion-du-sous-comite-du-cofi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.foodsovereignty.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Les petits p\u00eacheurs n\u00e9glig\u00e9s lors de la premi\u00e8re r\u00e9union du sous-comit\u00e9 du COFI"}]},{"@type":"WebSite","@id":"https:\/\/www.foodsovereignty.org\/fr\/#website","url":"https:\/\/www.foodsovereignty.org\/fr\/","name":"International Planning Committee for Food Sovereignty (IPC)","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.foodsovereignty.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.foodsovereignty.org\/fr\/#\/schema\/person\/2022da6fc0f89b23596d0a63d82b61e1","name":"ipc_staging","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fce93258e0a23ad6ba66052185f81fce65925c41d889b9d1b920a76951c434af?s=96&d=mm&r=g","caption":"ipc_staging"},"sameAs":["http:\/\/_"],"url":"https:\/\/www.foodsovereignty.org\/fr\/author\/ipc_staging\/"}]}},"_links":{"self":[{"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/posts\/1810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/comments?post=1810"}],"version-history":[{"count":3,"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/posts\/1810\/revisions"}],"predecessor-version":[{"id":3450,"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/posts\/1810\/revisions\/3450"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/media\/2509"}],"wp:attachment":[{"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/media?parent=1810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/categories?post=1810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.foodsovereignty.org\/fr\/wp-json\/wp\/v2\/tags?post=1810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}